{"id":110,"date":"2008-02-04T14:38:41","date_gmt":"2008-02-04T13:38:41","guid":{"rendered":"http:\/\/www.driczone.net\/blog\/invasion-en-cours\/"},"modified":"2008-02-04T14:38:41","modified_gmt":"2008-02-04T13:38:41","slug":"invasion-en-cours","status":"publish","type":"post","link":"https:\/\/www.inoffensif.net\/blog\/invasion-en-cours","title":{"rendered":"Invasion en cours"},"content":{"rendered":"<p>Il m&rsquo;en est arriv\u00e9 une bien bonne ce week-end. Figurez-vous que j&rsquo;\u00e9tais l\u00e0, tranquille chez moi avec ces cons de chats quand \u00e0 coup on sonne \u00e0 la porte. Intrigu\u00e9 mais confiant, j&rsquo;ouvre et tombe nez-\u00e0-nez avec une petite brune charg\u00e9e de valises et de sacs. J&rsquo;\u00e9tais pr\u00e8t \u00e0 lui claquer la porte au nez en disant que je n&rsquo;\u00e9tais pas int\u00e9ress\u00e9 par ses tapis, mais elle a forc\u00e9 le passage en grognant que c&rsquo;\u00e9tait lourd les sacs et que je pourrais l&rsquo;aider. Vous imaginez bien mon d\u00e9sarroi, la demoiselle semblait visiblement me conna\u00eetre.<\/p>\n<p>Une fois entr\u00e9e, elle a jet\u00e9 un regard vaguement d\u00e9go\u00fbt\u00e9 tout autour d&rsquo;elle avant de grogner que c&rsquo;\u00e9tait pas tr\u00e8s rang\u00e9, puis elle a vir\u00e9 les chats du canap\u00e9 (les pauvres en \u00e9taient outr\u00e9s) pour s&rsquo;y vautrer, pendant que je restais l&rsquo;air stup\u00e9fi\u00e9 et un peu idiot devant elle. Elle m&rsquo;a fait vrer mes affaires de mon armoire pour y mettre les siennes et elle a m\u00eame chang\u00e9 mon r\u00e9veil<sup id=\"rf1-110\"><a href=\"#fn1-110\" title=\"J&rsquo;y gagne au change cel\u00e0 dit, donc je ne vais pas me plaindre. Enfin pas trop.\" rel=\"footnote\">1<\/a><\/sup>.<\/p>\n<p>Sans vouloir me l&rsquo;avouer compl\u00e8tement, je crois qu&rsquo;une fille s&rsquo;est install\u00e9e chez moi&#8230;<\/p>\n<p STYLE=\"text-align: center\"><img SRC=\"https:\/\/blogmedia.driczone.net\/albane-debarque.gif\" ALT=\"Albane d\u00e9barque\" \/><\/p>\n<hr class=\"footnotes\"><ol class=\"footnotes\" style=\"list-style-type:decimal\"><li id=\"fn1-110\"><p >J&rsquo;y gagne au change cel\u00e0 dit, donc je ne vais pas me plaindre. Enfin pas trop.&nbsp;<a href=\"#rf1-110\" class=\"backlink\" title=\"Return to footnote 1.\">&#8617;<\/a><\/p><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Il m&rsquo;en est arriv\u00e9 une bien bonne ce week-end. Figurez-vous que j&rsquo;\u00e9tais l\u00e0, tranquille chez moi avec ces cons de chats quand \u00e0 coup on sonne \u00e0 la porte. Intrigu\u00e9 mais confiant, j&rsquo;ouvre et tombe nez-\u00e0-nez avec une petite brune charg\u00e9e de valises et de sacs. J&rsquo;\u00e9tais pr\u00e8t \u00e0 lui claquer la porte au nez en disant que je n&rsquo;\u00e9tais pas int\u00e9ress\u00e9 par ses tapis, mais elle a forc\u00e9 le passage en grognant que c&rsquo;\u00e9tait lourd les sacs et que <\/p>\n<p><a href=\"https:\/\/www.inoffensif.net\/blog\/invasion-en-cours\" class=\"button secondary small\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,13],"tags":[49,59,94,112,123],"class_list":["post-110","post","type-post","status-publish","format-standard","hentry","category-general","category-plaignez-moi","tag-chats","tag-copine","tag-home-sweet-home","tag-invasion","tag-ma-vie"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phuYx-1M","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":0,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}