{"id":131,"date":"2008-04-23T12:27:07","date_gmt":"2008-04-23T11:27:07","guid":{"rendered":"http:\/\/www.driczone.net\/blog\/?p=131"},"modified":"2008-04-23T12:27:07","modified_gmt":"2008-04-23T11:27:07","slug":"nostalgie-technologique","status":"publish","type":"post","link":"https:\/\/www.inoffensif.net\/blog\/nostalgie-technologique","title":{"rendered":"Nostalgie technologique"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin-left: 4px; margin-right: 4px;\" title=\"Un minitel dans toute sa splendeur\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/6\/6d\/Minitel_1.JPG\/180px-Minitel_1.JPG\" alt=\"Un minitel dans toute sa splendeur\" width=\"180\" height=\"203\" \/>Je vais vous entretenir aujourd&rsquo;hui du fleuron technologique fran\u00e7ais. Je ne parle bien s\u00fbr pas de la Citro\u00ebn 2CV, mais du Minitel.<\/p>\n<p>Le Minitel a \u00e9t\u00e9 invent\u00e9 par le Minist\u00e8re des Postes et T\u00e9l\u00e9communications en 1980, alors que j&rsquo;avais environ 0 ans.<\/p>\n<p>La plupart des d\u00e9cideurs de l&rsquo;\u00e9poque ont d\u00e9clar\u00e9 que c&rsquo;\u00e9tait compl\u00e8tement nul comme id\u00e9e, et que \u00e7a sentait le caca de panda. Val\u00e9ry Giscard d&rsquo;Estaing alors Pr\u00e9sident de la R\u00e9publique en vit un un jour au d\u00e9tour d&rsquo;une machine \u00e0 caf\u00e9 et s&rsquo;exclama : \u00ab\u00a0Mais c&rsquo;est top moumoute ce truc, j&rsquo;en veux un !\u00a0\u00bb. D\u00e8s lors, l&rsquo;ensemble de la classe politique ne cessa de s&rsquo;extasier devant tant de prouesse technologique.<\/p>\n<p>Pour ceux qui ont eu la chance de s&rsquo;en servir un jour, le Minitel c&rsquo;est avant tout des graphismes tout moches, une m\u00e9lodie de connexion semblable \u00e0 celle des modems 56k et inf\u00e9rieurs<sup id=\"rf1-131\"><a href=\"#fn1-131\" title=\"Les plus jeunes d&rsquo;entre nous n&rsquo;auront jamais la chance d&rsquo;\u00e9couter ce son si particulier qui entra\u00eenait un suspens insoutenable lors des (longues) connexions \u00e0 Internet avant l&rsquo;apparition de l&rsquo;ADSL et du c\u00e2ble. Petits cons de jeunes.\" rel=\"footnote\">1<\/a><\/sup> et une rapidit\u00e9 semblable au rythme effr\u00e9n\u00e9 des productions t\u00e9l\u00e9visuelles allemandes telles que Derrick.<\/p>\n<p>Bien vite le syst\u00e8me fut d\u00e9tourn\u00e9 de son utilisation de base, ce fut le d\u00e9but des messageries roses et des premiers tchats.<\/p>\n<p><a href=\"https:\/\/blogmedia.driczone.net\/3615vazi01ok_s.jpg\" class=\"thickbox no_icon\" ><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-133\" title=\"Affiche superbe de service minitel\" src=\"https:\/\/blogmedia.driczone.net\/3615vazi01ok_s.jpg\" alt=\"Affiche superbe de service minitel\" width=\"240\" height=\"172\" \/><\/a>Mais il restait un \u00e9cueil de taille pour les petits malins qui proposaient des services de dialogue en direct avec des filles pour le moins peu farouches (et qui \u00e9taient probablement en r\u00e9alit\u00e9 des hommes laids et pay\u00e9s pour \u00e7a), la question du visuel. Vu la qualit\u00e9 des graphismes, impossible d&rsquo;afficher des filles nues sur ce terminal. Julien Flanchet, responsable du service 3615 vienzy, d\u00e9clara en 1983 : \u00ab\u00a0Les photos de filles nues, faudra attendre l&rsquo;an 2000 pour les avoir !\u00a0\u00bb. Ce en quoi il avait presque raison, m\u00eame si le porno sur Internet a commenc\u00e9 bien avant. Les publicistes ont bien \u00e9videmment trouv\u00e9 la solution, ils d\u00e9port\u00e8rent les images suggestives et affriolantes sur les affiches publicitaires vantant les m\u00e9rites des services de messagerie \u00e0 caract\u00e8re coquin. Ce qui permit aux jeunes de mon \u00e2ge de se rincer l&rsquo;\u0153il ais\u00e9ment lorsqu&rsquo;ils \u00e9taient coinc\u00e9s dans les bouchons \u00e0 l&rsquo;arri\u00e8re de la voiture. Je ne les remercierai jamais assez pour leur courageux acte de d\u00e9bauche. Le Gouvernement en revanche finit par les remercier en les priant instamment mais un peu tardivement de ne pas exposer de viande fra\u00eeche \u00e0 la vue de tout le monde.<\/p>\n<p>On trouve d&rsquo;ailleurs sur ce site un peu bizarre quelques exemples d&rsquo;affiches du m\u00eame genre : <a title=\"Un site exemplaire, selon l'Association des automobilistes coinc\u00e9s dans les bouchons entre 1980 et 1990\" href=\"http:\/\/labellemusique.free.fr\/magazine\/pierrephoto.htm\" target=\"_blank\">Photographies de 3615<\/a>.<\/p>\n<p><a class=\"thickbox no_icon\" href=\"https:\/\/blogmedia.driczone.net\/minitel_beachvolley.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-130\" style=\"margin-left: 4px; margin-right: 4px;\" title=\"Superbe choix de couleurs\" src=\"https:\/\/blogmedia.driczone.net\/minitel_beachvolley.jpg\" alt=\"Superbe choix de couleurs\" width=\"200\" height=\"122\" \/><\/a>Mais le Minitel, ce n&rsquo;est pas que les messageries roses, c&rsquo;est aussi des services comme les classements des ligues sportives, des portails administratifs, des annuaires \u00e0 la pelle ! C&rsquo;\u00e9tait le bon temps du mauvais go\u00fbt colorim\u00e9trique \u00e0 la <a href=\"http:\/\/www.atchoumation.net\">Atchoumation.net<\/a>, comme en t\u00e9moigne la capture d&rsquo;\u00e9cran ci-contre.<\/p>\n<p>Il faut noter quand m\u00eame qu&rsquo;il existe encore des services \u00e0 la CPAM notamment accessibles seulement par Minitel. Comment Internet ? C&rsquo;est quoi ce truc ?!<\/p>\n<hr class=\"footnotes\"><ol class=\"footnotes\" style=\"list-style-type:decimal\"><li id=\"fn1-131\"><p >Les plus jeunes d&rsquo;entre nous n&rsquo;auront jamais la chance d&rsquo;\u00e9couter ce son si particulier qui entra\u00eenait un suspens insoutenable lors des (longues) connexions \u00e0 Internet avant l&rsquo;apparition de l&rsquo;ADSL et du c\u00e2ble. Petits cons de jeunes.&nbsp;<a href=\"#rf1-131\" class=\"backlink\" title=\"Return to footnote 1.\">&#8617;<\/a><\/p><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Je vais vous entretenir aujourd&rsquo;hui du fleuron technologique fran\u00e7ais. Je ne parle bien s\u00fbr pas de la Citro\u00ebn 2CV, mais du Minitel.<\/p>\n<p>Le Minitel a \u00e9t\u00e9 invent\u00e9 par le Minist\u00e8re des Postes et T\u00e9l\u00e9communications en 1980, alors que j&rsquo;avais environ 0 ans.<\/p>\n<p>La plupart des d\u00e9cideurs de l&rsquo;\u00e9poque ont d\u00e9clar\u00e9 que c&rsquo;\u00e9tait compl\u00e8tement nul comme id\u00e9e, et que \u00e7a sentait le caca de panda. Val\u00e9ry Giscard d&rsquo;Estaing alors Pr\u00e9sident de la R\u00e9publique en vit un un jour au d\u00e9tour d&rsquo;une machine \u00e0 <\/p>\n<p><a href=\"https:\/\/www.inoffensif.net\/blog\/nostalgie-technologique\" class=\"button secondary small\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,7],"tags":[93,110,130,176,177,187],"class_list":["post-131","post","type-post","status-publish","format-standard","hentry","category-articles-scientifiques","category-internetinformatique","tag-histoire","tag-informatique","tag-minitel","tag-science","tag-sexe","tag-technologie"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phuYx-27","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":0,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}