{"id":248,"date":"2009-02-23T14:49:29","date_gmt":"2009-02-23T12:49:29","guid":{"rendered":"http:\/\/www.driczone.net\/blog\/?p=248"},"modified":"2009-02-23T14:49:29","modified_gmt":"2009-02-23T12:49:29","slug":"ce-que-tu-peux-etre-nouille-mon-pauvre-marco","status":"publish","type":"post","link":"https:\/\/www.inoffensif.net\/blog\/ce-que-tu-peux-etre-nouille-mon-pauvre-marco","title":{"rendered":"Ce que tu peux \u00eatre nouille mon pauvre Marco"},"content":{"rendered":"<div style=\"width: 160px\" class=\"wp-caption alignleft\"><a class=\"thickbox no_icon\" href=\"https:\/\/blogmedia.driczone.net\/polo.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"La Polo, une voiture qui r\u00e9siste aux briques (m\u00eame aux grosses)\" src=\"https:\/\/blogmedia.driczone.net\/polo-150x101.jpg\" alt=\"\" width=\"150\" height=\"101\" \/><\/a><p class=\"wp-caption-text\">Illustration d&#39;un mauvais choix d&#39;illustration<\/p><\/div>\n<p>J&rsquo;ai achet\u00e9 r\u00e9cemment Kung Fu Panda (que je vous recommande vivement, surtout si vous avec d\u00e9j\u00e0 une vague connaissance des dessins anim\u00e9s et films se d\u00e9roulant dans la Chine antique), et il se trouve que le personnage principal (Po le Panda) est un super cuisinier en nouilles.<\/p>\n<p>La nouille, c&rsquo;est quand m\u00eame classe comme nom. Largement mieux que les spaghettis. De tout temps ces deux d\u00e9nominations se sont affront\u00e9es dans un combat sans merci, une saga fantastique intitul\u00e9e : \u00ab\u00a0La vengeance de la nouille carbonara\u00a0\u00bb.<\/p>\n<p>Les italiens ne la ram\u00e8nent pas trop lorsqu&rsquo;on leur parle de l&rsquo;origine des spaghettis, et pour cause : il a \u00e9t\u00e9 d\u00e9montr\u00e9 que c&rsquo;est gr\u00e2ce \u00e0 la Route de la Soie que la nouille a \u00e9t\u00e9 introduite en Europe par \u00a0Marco Polo<sup id=\"rf1-248\"><a href=\"#fn1-248\" title=\"M\u00eame si en fait il se peut que la nouille ait pr\u00e9c\u00e9d\u00e9 de peu ce bon Polo qui avait eu du retard suite \u00e0 une grosse diarh\u00e9e, mais ce sont des d\u00e9tails que les historiens n&rsquo;aiment pas trop aborder.\" rel=\"footnote\">1<\/a><\/sup>.<\/p>\n<p>Marco Polo est n\u00e9 le 15 septembre 1254, une ann\u00e9e que la plupart des gens qui l&rsquo;ont v\u00e9cu ont qualifi\u00e9 de \u00ab\u00a0bien, mais pas glop\u00a0\u00bb. On sait que son p\u00e8re \u00e9tait absent au moment de la naissance (une vieille tante malade \u00e0 visiter), mais ce qu&rsquo;on sait moins c&rsquo;est que sa m\u00e8re \u00e9tait \u00e9galement absente.<\/p>\n<p>C&rsquo;est donc par sa nounou qu&rsquo;il est \u00e9lev\u00e9, jusqu&rsquo;\u00e0 ce que ses parents rentrent enfin alors qu&rsquo;il a 17 ans. Le petit Marco ne peut pas blairer les fran\u00e7ais et particuli\u00e8rement leurs rois. Aussi lorsque Philippe le Hardi fut couronn\u00e9 en 1271, il demanda \u00e0 ses parents de quitter l&rsquo;Europe pour cause de voisinage (je cite) \u00ab\u00a0bruyant, malodorant et qui parle le fran\u00e7ais avec un accent d\u00e9plorable\u00a0\u00bb. Ses parents soupir\u00e8rent et affr\u00e8t\u00e8rent un navire pour la Chine o\u00f9 le papa de Marco avait quelques affaires qui tournent.<\/p>\n<p>A l&rsquo;instar des affaires qui tournent, les pouces de la famille Polo commenc\u00e8rent \u00e0 en faire de m\u00eame. Ils d\u00e9cid\u00e8rent donc de rendre une visite de courtoisie au grand Khan voisin, petit-fils de Gengis Khan et bien moins effront\u00e9 que son grand-p\u00e8re. En effet, ce personnage tr\u00e8s puissant r\u00e8gnait sur un Empire gigantesque, il avait donc autre chose \u00e0 faire que d&rsquo;aller piller ses voisins. Alors que l&rsquo;entrevue se d\u00e9roulait assez bien malgr\u00e9 un jeu de mots foireux de Papa Polo, le jeune Marco qui avait alors 20 ans se prit les pieds dans un tapis et alla s&rsquo;encastrer dans un vase, se coin\u00e7ant la t\u00eate dedans. L&rsquo;Empereur ne voulant pas casser son vase, ordonna qu&rsquo;on tranche la t\u00eate de ce maladroit pour la d\u00e9gager. Mais le bourreau bourr\u00e9 rata son coup et fracassa le vase en faisant une coupe de cheveux tr\u00e8s courte au petit Marco au passage.<\/p>\n<p>L&rsquo;Empereur y vit alors un pr\u00e9sage et d\u00e9cida de lui confier les r\u00eanes de son Empire, avant que ses conseillers inquiets pour leur gagne-pain ne lui sussurent de le nommer consultant externe \u00e0 la place. Ainsi Marco Polo passa-t-il son temps \u00e0 accomplir des missions pour l&rsquo;Empereur. On lui demanda ainsi d&rsquo;escorter une princesse (qui malgr\u00e9 toutes les avances de Marco ne c\u00e9da pas \u00e0 la cabriole. Marco raconta dans ses m\u00e9moires que de toute fa\u00e7on elle \u00e9tait m\u00eame pas belle), de r\u00e9guler des trucs, de d\u00e9velopper des choses et de trancher d\u00e9finitivement la question de\u00a0 savoir qui de l&rsquo;\u00e9l\u00e9phant ou du rhinoc\u00e9ros \u00e9tait le plus bal\u00e8ze. Les conclusions de ce dernier rapport conduisirent \u00e0 l&rsquo;assassinat du premier ministre de l&#8217;empereur, qui \u00e9tait par ailleurs une vile crapule. On ne retrouva jamais le rapport en lui-m\u00eame, bien que des sources bien inform\u00e9es et pas trop alcoolis\u00e9es affirment que les dirigeants chinois le gardent dans un endroit secret appel\u00e9 \u00ab\u00a0L&rsquo;endroit secret le plus secret parmis les grands endroits secrets\u00a0\u00bb.<\/p>\n<p>Au bout d&rsquo;un moment, Marco Polo qui avait entretemps mis pas mal d&rsquo;argent de c\u00f4t\u00e9 en magouillant comme un goret lors de ses missions<sup id=\"rf2-248\"><a href=\"#fn2-248\" title=\"Il est possible que \u00e7a soit authentique, puisque dans son livre M. Polo ne dit mentionne pas la provenance de sa fortune.\" rel=\"footnote\">2<\/a><\/sup> se rendit chez l&rsquo;Empereur de Chine, le Khan Krelat (les historiens occidentaux renomm\u00e8rent plus tard cet empereur en Khan K\u016bbila\u00ef, parce que \u00e7a faisait plus classe et que c&rsquo;\u00e9tait plein de lettres avec des accents bizarres) et lui tint \u00e0 peu pr\u00e8s ce langage :<\/p>\n<p>\u00ab\u00a0&#8211; Mon p&rsquo;tit Khan, on a bien rigol\u00e9 mais l\u00e0 faut que je rentre \u00e0 Venise. De toute fa\u00e7on notre idylle \u00e9tait impossible.<\/p>\n<p>&#8211; Ok boy, tire-toi de mon palais. A plus mec ! Lui r\u00e9pondit le Khan.<\/p>\n<p>&#8211; Ouech mec.\u00a0\u00bb<\/p>\n<p>Ainsi Marco rentra \u00e0 Venise avec beaucoup d&rsquo;esbrouffe, allant m\u00eame jusqu&rsquo;\u00e0 dire qu&rsquo;il \u00e9tait devenu le roi du monde et qu&rsquo;il avait couch\u00e9 avec la princesse d&rsquo;Iran. C&rsquo;est probablement son incroyable vantardise qui conduisit pas mal de monde \u00e0 douter de ses r\u00e9cits il faut le dire un peu acadabrantesques par moments. Parce qu&rsquo;autant on peut croire qu&rsquo;il fut un fin n\u00e9gociateur ou un enqu\u00eateur rus\u00e9, autant le fait qu&rsquo;il mis une branl\u00e9e aux Terribles Ninjas Cruels et Mortels de la Nuit reste assez peu cr\u00e9dible.<\/p>\n<p>Marco joua un peu \u00e0 la guerre, fut fait prisonnier et dicta son livre en prison \u00e0 son co-d\u00e9tenu qui dut pour le coup apprendre \u00e0 \u00e9crire, ce qui explique l&rsquo;orthographe plus qu&rsquo;approximative du premier jet de ce r\u00e9cit. A sa sortie de prison il se jeta sur la premi\u00e8re fille pas trop mal foutue qu&rsquo;il trouva et lui fit 3 filles en moins de 5 mois (les historiens s&rsquo;entretuent encore sur cet exploit, d&rsquo;aucuns pensent qu&rsquo;il pourrait avoir encore une fois exag\u00e9r\u00e9 la r\u00e9alit\u00e9). Il est probable qu&rsquo;il devint un type puissant et magouilleur, mais il mourut quand m\u00eame comme tout le monde en 1324. Tout le monde fut tr\u00e8s triste lors de son enterrement parce qu&rsquo;on ne savait pas au moment de sa mort o\u00f9 il avait planqu\u00e9 ses pierres pr\u00e9cieuses. Heureusement comme Marco perdait la m\u00e9moire sur la fin, il avait not\u00e9 l&#8217;emplacement sur son garde-manger et tout le monde fut finalement bien content.<\/p>\n<p>Sources : <a title=\"Wikip\u00e9dia, une source consid\u00e9r\u00e9e comme presque fiable par les \u00e9leveurs de graisse du Tenessee\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Marco_Polo\" target=\"_blank\">wikipedia<\/a>, <a title=\"Il para\u00eet que Marco Polo pr\u00e9f\u00e9rait de loin  les nouilles aux spaghettis, et on le comprend !\" href=\"http:\/\/www.marcopolo.fr\/\" target=\"_blank\">marco polo foods<\/a>, \u00a0<a title=\"Marco Polo, le retour de la vengeance du terrible Khan Ping Kar\" href=\"http:\/\/www.touteleurope.fr\/fr\/divers\/toutes-les-informations-pratiques\/information-pratique\/afficher\/fiche_infocard\/188\/t\/44383\/from\/2608\/card\/marco-polo-ameliorer-les-performances-environnementales-du-systeme-de-transport-de-marchandises.html\" target=\"_blank\">programme Marco Polo<\/a>.<\/p>\n<hr class=\"footnotes\"><ol class=\"footnotes\" style=\"list-style-type:decimal\"><li id=\"fn1-248\"><p >M\u00eame si en fait il se peut que la nouille ait pr\u00e9c\u00e9d\u00e9 de peu ce bon Polo qui avait eu du retard suite \u00e0 une grosse diarh\u00e9e, mais ce sont des d\u00e9tails que les historiens n&rsquo;aiment pas trop aborder.&nbsp;<a href=\"#rf1-248\" class=\"backlink\" title=\"Return to footnote 1.\">&#8617;<\/a><\/p><\/li><li id=\"fn2-248\"><p >Il est possible que \u00e7a soit authentique, puisque dans son livre M. Polo ne dit mentionne pas la provenance de sa fortune.&nbsp;<a href=\"#rf2-248\" class=\"backlink\" title=\"Return to footnote 2.\">&#8617;<\/a><\/p><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p class=\"wp-caption-text\">Illustration d&#39;un mauvais choix d&#39;illustration<\/p>\n<p>J&rsquo;ai achet\u00e9 r\u00e9cemment Kung Fu Panda (que je vous recommande vivement, surtout si vous avec d\u00e9j\u00e0 une vague connaissance des dessins anim\u00e9s et films se d\u00e9roulant dans la Chine antique), et il se trouve que le personnage principal (Po le Panda) est un super cuisinier en nouilles.<\/p>\n<p>La nouille, c&rsquo;est quand m\u00eame classe comme nom. Largement mieux que les spaghettis. De tout temps ces deux d\u00e9nominations se sont affront\u00e9es dans un combat sans merci, une saga <\/p>\n<p><a href=\"https:\/\/www.inoffensif.net\/blog\/ce-que-tu-peux-etre-nouille-mon-pauvre-marco\" class=\"button secondary small\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[30,44,47,51,52,55,57,93,148,164],"class_list":["post-248","post","type-post","status-publish","format-standard","hentry","category-articles-scientifiques","tag-biographie","tag-celebre","tag-charlatan","tag-chine","tag-chinois","tag-commercial","tag-conquete-du-monde","tag-histoire","tag-paulo","tag-recit"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phuYx-40","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/comments?post=248"}],"version-history":[{"count":0,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/248\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/media?parent=248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/categories?post=248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/tags?post=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}