{"id":409,"date":"2010-01-18T16:54:43","date_gmt":"2010-01-18T15:54:43","guid":{"rendered":"http:\/\/www.driczone.net\/blog\/?p=409"},"modified":"2010-01-18T16:54:43","modified_gmt":"2010-01-18T15:54:43","slug":"note-de-papa-niais","status":"publish","type":"post","link":"https:\/\/www.inoffensif.net\/blog\/note-de-papa-niais","title":{"rendered":"Note de papa niais"},"content":{"rendered":"<p style=\"text-align: left;\">Rapha\u00ebl a pour joli surnom Godzilla, \u00e0 cause de sa tendance marqu\u00e9e \u00e0 grogner en agitant les bras comme Godzilla quand il part se promener dans Tokio (dans les premiers films de Godzilla, pas dans le remake am\u00e9ricain). Cependant, il lui arrive aussi de faire des jolis sourires.<\/p>\n<p style=\"text-align: center;\">[stream flv=x:\/www.driczone.net\/blog\/wp-content\/uploads\/raphael.flv embed=false share=false width=320 height=240 dock=true controlbar=over bandwidth=med autostart=false \/]<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: left;\">Oui, cette note est niaise. Si vous n&rsquo;aimez pas les gamins elle n&rsquo;aura aucun int\u00e9r\u00eat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: left;\">Rapha\u00ebl a pour joli surnom Godzilla, \u00e0 cause de sa tendance marqu\u00e9e \u00e0 grogner en agitant les bras comme Godzilla quand il part se promener dans Tokio (dans les premiers films de Godzilla, pas dans le remake am\u00e9ricain). Cependant, il lui arrive aussi de faire des jolis sourires.<\/p>\n<p style=\"text-align: center;\">[stream flv=x:\/www.driczone.net\/blog\/wp-content\/uploads\/raphael.flv embed=false share=false width=320 height=240 dock=true controlbar=over bandwidth=med autostart=false \/]<\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: left;\">Oui, cette note est niaise. Si vous n&rsquo;aimez pas les gamins elle n&rsquo;aura aucun int\u00e9r\u00eat.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14],"tags":[27,88,90,106,117,123,194],"class_list":["post-409","post","type-post","status-publish","format-standard","hentry","category-regardez-ecoutez-jouez","tag-bebe","tag-gamin","tag-genial","tag-idee-venue-sur-le-coup","tag-la-famille","tag-ma-vie","tag-video"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phuYx-6B","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/comments?post=409"}],"version-history":[{"count":0,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/409\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/media?parent=409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/categories?post=409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/tags?post=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}