{"id":79,"date":"2007-07-11T11:57:04","date_gmt":"2007-07-11T10:57:04","guid":{"rendered":"http:\/\/www.driczone.net\/blog\/un-gars-globalement-inoffensif\/"},"modified":"2007-07-11T11:57:04","modified_gmt":"2007-07-11T10:57:04","slug":"un-gars-globalement-inoffensif","status":"publish","type":"post","link":"https:\/\/www.inoffensif.net\/blog\/un-gars-globalement-inoffensif","title":{"rendered":"Un gars globalement inoffensif"},"content":{"rendered":"<p>Il existe deux cat\u00e9gories de personnes sur Terre : ceux qui lisent mon blog, les autres, et ceux qui ne savent pas compter. Bref, je suis s\u00fbr que vous br\u00fblez d&rsquo;impatience d&rsquo;en apprendre plus sur ma vie.<\/p>\n<p>Je suis n\u00e9 \u00e0 l&rsquo;\u00e2ge de 3 ans, ce qui peut para\u00eetre un peu tardif mais j&rsquo;aime prendre mon temps. De plus \u00e7a m&rsquo;a permis de savoir d\u00e9j\u00e0 marcher et parler d\u00e8s la naissance,\u00a0 ce qui est beaucoup plus classe que la plupart des bouts de viande braillards et plein de fuites qu&rsquo;on voit d&rsquo;habitude.<\/p>\n<p>Tout petit d\u00e9j\u00e0, je savais que j&rsquo;\u00e9tais vou\u00e9 \u00e0 un destin extraordinairement commun et banal. Bien s\u00fbr il m&rsquo;est arriv\u00e9 des choses \u00e9tranges, comme de d\u00e9couvrir qu&rsquo;il \u00e9tait possible d&rsquo;\u00e9garer un appareil dentaire dans un bus ou que la retransmission des d\u00e9bats de l&rsquo;Assembl\u00e9e G\u00e9n\u00e9rale sont d&rsquo;un ennui assez puissant. J&rsquo;ai \u00e9galement agonis\u00e9 pendant toute une journ\u00e9e dans la cour de mon \u00e9cole sous l&rsquo;oeil indiff\u00e9rent d&rsquo;\u00e0 peu pr\u00e8s tout ce qui poss\u00e9dait des yeux \u00e0 cette \u00e9poque. Finalement je ne m&rsquo;en suis pas trop mal sorti dans la vie puisque je ne suis mort que 2 fois depuis ma naissance et \u00e0 chaque fois je n&rsquo;\u00e9tais pas l\u00e0, je n&rsquo;ai donc pas trop souffert.<\/p>\n<p>A 12 ans j&rsquo;ai sauv\u00e9 le monde des d\u00e9marcheurs en assurances en inventant le massage cardiaque. L&rsquo;ann\u00e9e suivante, j&rsquo;ai d\u00e9couvert l&rsquo;eau chaude et tout de suite apr\u00e8s l&rsquo;eau froide. A 15 ans, alors que j&rsquo;allais remettre en cause le principe de la roue qui me semblait \u00eatre totalement bidon, j&rsquo;ai pu tout \u00e0 coup \u00e9crire mon pr\u00e9nom correctement. L&#8217;emsemble de mon quartier s&rsquo;est alors rassembl\u00e9 pour chanter mes louanges avant de me jeter des petits cailloux<sup id=\"rf1-79\"><a href=\"#fn1-79\" title=\"Quand je raconte cette anecdote, les gens sont toujours horrifi\u00e9s. Pourtant il n&rsquo;y a pas de quoi, c&rsquo;\u00e9tait des tout petits cailloux qui ne faisaient m\u00eame pas mal. Enfin presque pas.\" rel=\"footnote\">1<\/a><\/sup>.<\/p>\n<p>Arriv\u00e9 au lyc\u00e9e je me suis plong\u00e9 \u00e0 bras ouverts dans la coca\u00efne. C&rsquo;est ainsi que j&rsquo;ai pu entamer ma carri\u00e8re de chanteur de vari\u00e9t\u00e9, encha\u00eenant les plateaux c\u00e9l\u00e8bres comme Taratatouf, La Chance aux Poivrots, Star Rat\u00e9lbustuva\u00eatrenrtard, et diverses autres \u00e9missions politiques de fin de soir\u00e9e. Les filles se jetaient sur moi pour me faire taire, je chantais devant des salles vides, on me jetait des tomates, c&rsquo;\u00e9tait vraiment la belle vie.<\/p>\n<p>J&rsquo;ai pass\u00e9 mon bac avec succ\u00e8s sur un coup de bluff en 1998, pr\u00e9textant un coma et une jambe de bois pour sauter la plupart des \u00e9preuves. Aux oraux j&rsquo;ai pris la sage pr\u00e9caution de manger les 10 aliments qui donnent l&rsquo;haleine la plus f\u00e9tide du monde, ce qui m&rsquo;a permis de battre le record de la plus haute note en 20 secondes de temps de passage.<\/p>\n<p>Arriv\u00e9 en BTS d&rsquo;informatique, j&rsquo;ai d\u00e9couvert le monde fascinant des stages minables, devant chaque semaine passer une journ\u00e9e en entreprise \u00e0 faire des bo\u00eetes en carton ou classer des dossiers avant que mes professeurs, sages r\u00e9serves ambulantes d&rsquo;un savoir incommensurable me remettent dans le droit chemin, ce qui m&rsquo;a permis de d\u00e9velopper dans mon garage un petit logiciel appel\u00e9 Fen\u00eatres, que j&rsquo;ai depuis revendu \u00e0 un am\u00e9ricain<sup id=\"rf2-79\"><a href=\"#fn2-79\" title=\"Quel gros na\u00eff ce ricain, \u00e7a valait que dalle ce truc. En revanche ma version n&rsquo;\u00e9tait pas buggu\u00e9e, elle.\" rel=\"footnote\">2<\/a><\/sup> dont plus personne n&rsquo;a entendu parler. J&rsquo;ai eu m\u00f4n dipl\u00f4me facilement, le recevant par la poste avec la mention \u00ab\u00a0<em>Ne revenez plus, merci<\/em>.\u00a0\u00bb.<\/p>\n<p>En 2001, suite \u00e0 un internement en h\u00f4pital psychiatrique j&rsquo;ai provoqu\u00e9 le suicide de 12 m\u00e9decins. Le directeur enchant\u00e9 m&rsquo;a donc embauch\u00e9 en tant qu&rsquo;informaticien, me donnant en sous-main la permission de tuer des gens devenus encombrants pour cause de surcharge pond\u00e9rale.<\/p>\n<p>Un autre jour je vous raconterai l&rsquo;histoire grotesque de Chaussette le Chat, pour l&rsquo;instant je dois d\u00e9couvrir ce qui allume la lumi\u00e8re dans mon bureau.<\/p>\n<hr class=\"footnotes\"><ol class=\"footnotes\" style=\"list-style-type:decimal\"><li id=\"fn1-79\"><p >Quand je raconte cette anecdote, les gens sont toujours horrifi\u00e9s. Pourtant il n&rsquo;y a pas de quoi, c&rsquo;\u00e9tait des tout petits cailloux qui ne faisaient m\u00eame pas mal. Enfin presque pas.&nbsp;<a href=\"#rf1-79\" class=\"backlink\" title=\"Return to footnote 1.\">&#8617;<\/a><\/p><\/li><li id=\"fn2-79\"><p >Quel gros na\u00eff ce ricain, \u00e7a valait que dalle ce truc. En revanche ma version n&rsquo;\u00e9tait pas buggu\u00e9e, elle.&nbsp;<a href=\"#rf2-79\" class=\"backlink\" title=\"Return to footnote 2.\">&#8617;<\/a><\/p><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Il existe deux cat\u00e9gories de personnes sur Terre : ceux qui lisent mon blog, les autres, et ceux qui ne savent pas compter. Bref, je suis s\u00fbr que vous br\u00fblez d&rsquo;impatience d&rsquo;en apprendre plus sur ma vie.<\/p>\n<p>Je suis n\u00e9 \u00e0 l&rsquo;\u00e2ge de 3 ans, ce qui peut para\u00eetre un peu tardif mais j&rsquo;aime prendre mon temps. De plus \u00e7a m&rsquo;a permis de savoir d\u00e9j\u00e0 marcher et parler d\u00e8s la naissance,\u00a0 ce qui est beaucoup plus classe que la plupart des <\/p>\n<p><a href=\"https:\/\/www.inoffensif.net\/blog\/un-gars-globalement-inoffensif\" class=\"button secondary small\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,6],"tags":[35,72,25,110,123,185],"class_list":["post-79","post","type-post","status-publish","format-standard","hentry","category-divagations-quelconques","category-general","tag-boulet","tag-drogue","tag-etrange","tag-informatique","tag-ma-vie","tag-taf"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phuYx-1h","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":0,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/79\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/media?parent=79"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/categories?post=79"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/tags?post=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}