{"id":95,"date":"2007-09-30T17:25:04","date_gmt":"2007-09-30T16:25:04","guid":{"rendered":"http:\/\/www.driczone.net\/blog\/vous-avez-demande-police-ne-quittez-pas-12\/"},"modified":"2007-09-30T17:25:04","modified_gmt":"2007-09-30T16:25:04","slug":"vous-avez-demande-police-ne-quittez-pas-12","status":"publish","type":"post","link":"https:\/\/www.inoffensif.net\/blog\/vous-avez-demande-police-ne-quittez-pas-12","title":{"rendered":"Vous avez demand\u00e9 Police, ne quittez pas&#8230; (1\/2)"},"content":{"rendered":"<p>Comme la journ\u00e9e d&rsquo;hier a \u00e9t\u00e9 longue, j&rsquo;ai astucieusement choisi de la relater en deux parties, comme les t\u00e9l\u00e9films moisis de TF1 ou M6. Bien. Pour situer un peu les faits, il faut rappeler que la veille c&rsquo;\u00e9tait le tournoi de rentr\u00e9e du volley, qui s&rsquo;est termin\u00e9 nettement apr\u00e8s l&rsquo;heure du crime.<\/p>\n<p>Samedi matin donc, rendez-vous 10h et demi au parking de l&rsquo;autoroute de Bourges. J&rsquo;ai quand m\u00eame accompli l&rsquo;exploit d&rsquo;arriver \u00e0 l&rsquo;heure, grapillant m\u00eame cinq minutes sur l&rsquo;horaire pr\u00e9vue<sup id=\"rf1-95\"><a href=\"#fn1-95\" title=\"Cet exploit aurait m\u00e9rit\u00e9 d&rsquo;\u00eatre m\u00e9diatis\u00e9 \u00e0 sa juste valeur mais tant pis, je me rattraperais en le mentionnant dans mes m\u00e9moires quand je serais riche et c\u00e9l\u00e8bre.\" rel=\"footnote\">1<\/a><\/sup>. 5 minutes plus tard, alors que tout le monde est pr\u00eat et qu&rsquo;Agn\u00e8s lance pour blaguer \u00ab\u00a0Est-ce que tout le monde a son billet pour le concert ?\u00a0\u00bb, je me rend compte qu&rsquo;une fois de plus ma r\u00e9putation de boulet se justifie, le billet tr\u00f4ne en effet bien en \u00e9vidence chez moi, il a fallu y retourner pour le r\u00e9cup\u00e9r\u00e9r.<\/p>\n<p>Je vous passe le trajet jusqu&rsquo;\u00e0 la capitale, il est inint\u00e9ressant. Une fois gar\u00e9s (et apr\u00e8s avoir roul\u00e9 et reroul\u00e9 dans une belle bouse de chien assez odorante), direction Mc Do pour savourer une ration de lipides bien m\u00e9rit\u00e9e. Pour info les mis\u00e9rables salari\u00e9s des Mc Do de Bourges peuvent \u00eatre fiers d&rsquo;\u00eatre dix fois plus efficaces que leurs homologues parisiens alors qu&rsquo;ils sont moins nombreux. Je passe sur l&rsquo;\u00e9tat g\u00e9n\u00e9ral du \u00ab\u00a0restaurant\u00a0\u00bb, qui \u00e9tait uniform\u00e9ment recouvert d&rsquo;une couche de graisse. Les serveurs n&rsquo;\u00e9taient pas en reste, avec leurs t-shirts tach\u00e9s et d\u00e9pouill\u00e9s (v\u00e9ridique).<\/p>\n<p>Nous avons eu la chance d&rsquo;assister \u00e0 une descente de l&rsquo;inspection sanitaire,\u00a0c&rsquo;\u00e9tait tr\u00e8s impressionnant. Nous mangions tranquillement quand tout \u00e0 coup il y a eu un gros bang, des types v\u00eatues d&rsquo;une combinaison blanche ont travers\u00e9 les fen\u00eatres et nous ont mis en joue, ma\u00eetrisant les serveurs et assommant le manager qui tentait de s&rsquo;enfuir. Puis leur chef est entr\u00e9, un petit type tout insignifiant, habill\u00e9 d&rsquo;un costume noir mal taill\u00e9 et de grosses lunettes marron.\u00a0Il a regard\u00e9 un peu partout, flairant de ci-de-l\u00e0 en fron\u00e7ant le nez, puis il a abattu un serveur \u00e0 bout portant pour \u00eatre s\u00fbr d&rsquo;avoir l&rsquo;attention de tout le monde. Il a ensuite fait tout un discours sur la n\u00e9cessit\u00e9 de vivre en civilis\u00e9s et de ne pas c\u00e9der \u00e0 la facilit\u00e9 en se vautrant dans la fange et tout. Puis il a craqu\u00e9 une allumette et l&rsquo;a lanc\u00e9 sur le comptoir. Avec l&rsquo;huile et la graisse le Mc Do a commenc\u00e9 \u00e0 prendre feu, donc on ne s&rsquo;est pas attard\u00e9s et\u00a0on a fil\u00e9 dans le Quick juste \u00e0 c\u00f4t\u00e9.\u00a0Pas de bol, l&rsquo;inspection sanitaire venait d&rsquo;y passer et avait d\u00e9j\u00e0 tu\u00e9 tout le monde.<\/p>\n<p>Du coup nous sommes partis zoner sur les Champs Elys\u00e9es, lieu privil\u00e9gi\u00e9 o\u00f9 on peut voir des clochards cotoyer des mecs qui s&#8217;emmerdent comme des rats morts \u00e0 la terrasse d&rsquo;un caf\u00e9 o\u00f9 la moindre consommation co\u00fbte un demi-rein au quidam moyen. On y croise des tenues vestimentaires \u00e9tranges, comme une femme habill\u00e9e d&rsquo;un grand abat-jour violet, des gens qui portent des lunettes plus grosses qu&rsquo;une baie vitr\u00e9e<sup id=\"rf2-95\"><a href=\"#fn2-95\" title=\"Au nom de tous les fans de Rick Hunter, merci \u00e0 eux.\" rel=\"footnote\">2<\/a><\/sup> et une femme qui arborait des bottes en fourrure du plus mauvais go\u00fbt (elle aurait march\u00e9 dans un chat d&rsquo;apr\u00e8s Mehdi).<\/p>\n<p>Vous le savez, je n&rsquo;h\u00e9site pas \u00e0 donner de ma personne pour vous offrir la meilleur information possible. J&rsquo;ai donc personnellement test\u00e9 les si\u00e8ges des boutiques Adidas et Nike, c&rsquo;est Nike qui l&#8217;emporte haut la main m\u00eame si en terme de confort pur c&rsquo;est pas vraiment \u00e7a. Nous sommes pass\u00e9 \u00e0 Virgin, et ces gens sont compl\u00e8tement inconscients : ils laissent tra\u00eener la saison 5 de la Petite maison dans la prairie en Dvd juste \u00e0 l&rsquo;entr\u00e9e. Les gens avec moi se sont jet\u00e9s dessus, bataillant sur des points obcurs du sc\u00e9nario (\u00ab\u00a0Mais siii, l\u00e0 elle pas encoire aveugle, il se passe plein de trucs apr\u00e8s !\u00a0\u00bb &#8211; v\u00e9ridique malheureusement). Bien \u00e9videmment avec les histoires de fans, c&rsquo;en est rapidement venu aux mains et des vigiles sont intervenus avec leurs matraques. Ils nous ont foutu dehors apr\u00e8s nous avoir copieusement tabass\u00e9s mais ils ont eu la gentillesse de ne pas trop taper les filles sur le visage et de ne pas viser sous la ceinture pour les gars.<\/p>\n<p>j&rsquo;en viens au scandale du jour : la boutique Disney. en y entrant nous f\u00fbmmes imm\u00e9diatement frapp\u00e9s par la chaleur et le bruit. On aurait dit que les marmots les plus bruyants et p\u00e9nibles du monde se sont tous donn\u00e9 rendez-vous ici pour la Convention Internationale des Gamins P\u00e9nibles. Mais ce n&rsquo;\u00e9tait pas tout : devant nos yeux s&rsquo;\u00e9talait ce qui d\u00e9passe probablement la mascarade de la mort de Kennedy et du nuage de\u00a0Tchernobyle.\u00a0Le coeur du probl\u00e8me, c&rsquo;est\u00a0les peluches officielles du dessin anim\u00e9 Ratatouille<sup id=\"rf3-95\"><a href=\"#fn3-95\" title=\"Je conseille d&rsquo;ailleurs ce film a tous les adultes qui aiment les dessins anim\u00e9s. Pour les gamins \u00e7a doit \u00eatre moins bien enrevanche.\" rel=\"footnote\">3<\/a><\/sup>. Passe encore qu&rsquo;elles soient fabriqu\u00e9es par des enfants chinois dans des ateliers du centre de la Chine (j&rsquo;ai v\u00e9rifi\u00e9, c&rsquo;est marqu\u00e9 sur l&rsquo;\u00e9tiquette), c&rsquo;est surtout qu&rsquo;elles sont laides \u00e0 vomir ! Je veux bien croire que le rat du dessin anim\u00e9 n&rsquo;est pas aussi mignon \u00e0 la base qu&rsquo;un nemo ou qu&rsquo;un stitch, mais de l\u00e0 \u00e0 en faire une sorte de d\u00e9pouille miteuse avec des yeux exhorbit\u00e9s<sup id=\"rf4-95\"><a href=\"#fn4-95\" title=\"Astuce de Dric : pour rentabiliser l&rsquo;achat de cette peluche, prenez-vous en photo en train de l&rsquo;\u00e9trangler, l&rsquo;effet est saisissant.\" rel=\"footnote\">4<\/a><\/sup> il y avait une marge qu&rsquo;ils ont converti en b\u00e9n\u00e9fice net pour la soci\u00e9t\u00e9 Disney.<\/p>\n<p>La suite au prochain num\u00e9ro (le num\u00e9ro 2 donc).<\/p>\n<hr class=\"footnotes\"><ol class=\"footnotes\" style=\"list-style-type:decimal\"><li id=\"fn1-95\"><p >Cet exploit aurait m\u00e9rit\u00e9 d&rsquo;\u00eatre m\u00e9diatis\u00e9 \u00e0 sa juste valeur mais tant pis, je me rattraperais en le mentionnant dans mes m\u00e9moires quand je serais riche et c\u00e9l\u00e8bre.&nbsp;<a href=\"#rf1-95\" class=\"backlink\" title=\"Return to footnote 1.\">&#8617;<\/a><\/p><\/li><li id=\"fn2-95\"><p >Au nom de tous les fans de Rick Hunter, merci \u00e0 eux.&nbsp;<a href=\"#rf2-95\" class=\"backlink\" title=\"Return to footnote 2.\">&#8617;<\/a><\/p><\/li><li id=\"fn3-95\"><p >Je conseille d&rsquo;ailleurs ce film a tous les adultes qui aiment les dessins anim\u00e9s. Pour les gamins \u00e7a doit \u00eatre moins bien enrevanche.&nbsp;<a href=\"#rf3-95\" class=\"backlink\" title=\"Return to footnote 3.\">&#8617;<\/a><\/p><\/li><li id=\"fn4-95\"><p >Astuce de Dric : pour rentabiliser l&rsquo;achat de cette peluche, prenez-vous en photo en train de l&rsquo;\u00e9trangler, l&rsquo;effet est saisissant.&nbsp;<a href=\"#rf4-95\" class=\"backlink\" title=\"Return to footnote 4.\">&#8617;<\/a><\/p><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Comme la journ\u00e9e d&rsquo;hier a \u00e9t\u00e9 longue, j&rsquo;ai astucieusement choisi de la relater en deux parties, comme les t\u00e9l\u00e9films moisis de TF1 ou M6. Bien. Pour situer un peu les faits, il faut rappeler que la veille c&rsquo;\u00e9tait le tournoi de rentr\u00e9e du volley, qui s&rsquo;est termin\u00e9 nettement apr\u00e8s l&rsquo;heure du crime.<\/p>\n<p>Samedi matin donc, rendez-vous 10h et demi au parking de l&rsquo;autoroute de Bourges. J&rsquo;ai quand m\u00eame accompli l&rsquo;exploit d&rsquo;arriver \u00e0 l&rsquo;heure, grapillant m\u00eame cinq minutes sur l&rsquo;horaire pr\u00e9vue1. 5 <\/p>\n<p><a href=\"https:\/\/www.inoffensif.net\/blog\/vous-avez-demande-police-ne-quittez-pas-12\" class=\"button secondary small\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,14],"tags":[20,34,55,56,58,88,120,123,142,151,175],"class_list":["post-95","post","type-post","status-publish","format-standard","hentry","category-general","category-regardez-ecoutez-jouez","tag-amis","tag-bouffe","tag-commercial","tag-concert","tag-conseil","tag-gamin","tag-les-gens","tag-ma-vie","tag-objets","tag-periple","tag-scandale"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/phuYx-1x","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":0,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/posts\/95\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/media?parent=95"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/categories?post=95"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoffensif.net\/blog\/wp-json\/wp\/v2\/tags?post=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}